{"id":4417,"date":"2021-03-26T12:00:00","date_gmt":"2021-03-26T11:00:00","guid":{"rendered":"https:\/\/www.focus-obs.org\/documents\/madagascar-towards-better-protection-for-human-rights-defenders\/"},"modified":"2022-10-27T17:23:32","modified_gmt":"2022-10-27T15:23:32","slug":"madagascar-atelier-de-lishr-sur-le-projet-de-loi-sur-les-defenseur%c2%b7e%c2%b7s-des-droits-humains","status":"publish","type":"documents","link":"https:\/\/www.focus-obs.org\/fr\/documents\/madagascar-atelier-de-lishr-sur-le-projet-de-loi-sur-les-defenseur%c2%b7e%c2%b7s-des-droits-humains\/","title":{"rendered":"Madagascar: Atelier de l&rsquo;ISHR sur le projet de loi sur les d\u00e9fenseur\u00b7e\u00b7s des droits humains"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00ab\u00a0<strong>A Madagascar les attaques contre les d\u00e9fenseur.es des droits humains et les lanceurs d\u2019alerte se multiplient. Un avant-projet de loi sur la protection des d\u00e9fenseur.es avait \u00e9t\u00e9 pr\u00e9par\u00e9 en 2018 par le Minist\u00e8re de la Justice malgache, avec l\u2019appui du Haut-commissariat des Nations Unies pour les Droits de l\u2019Homme, et soumis \u00e0 une premi\u00e8re consultation de la soci\u00e9t\u00e9 civile mais sans r\u00e9elle avanc\u00e9es depuis. Dans le but de relancer le processus vers l\u2019adoption d\u2019une telle loi, la soci\u00e9t\u00e9 civile ainsi que le Haut Conseil pour la D\u00e9fense de la D\u00e9mocratie et de l\u2019Etat de Droit ont tout deux organis\u00e9 des ateliers successifs visant la r\u00e9vision et l\u2019adoption d\u2019un projet de loi en accord avec les standards internationaux.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019atelier, co-organis\u00e9 par ISHR et Transparency International \u2013 Madagascar, s\u2019est d\u00e9roul\u00e9 en ligne les 22 et 23 Mars 2021. Il a donn\u00e9 l\u2019opportunit\u00e9 \u00e0 la soci\u00e9t\u00e9 civile de revoir et am\u00e9liorer les projets de loi sugg\u00e9r\u00e9s par le Minist\u00e8re de la Justice et le Haut Conseil pour la D\u00e9fense de la D\u00e9mocratie et de l\u2019Etat de Droit (HCDDED) en amont de l\u2019atelier organis\u00e9 les jours suivants par le HCDDED qui visait la validation d\u2019un projet de loi enti\u00e8rement bas\u00e9 sur la <a href=\"https:\/\/www.focus-obs.org\/documents\/model-law\/\" target=\"_blank\" rel=\"noreferrer noopener\">Loi type<\/a> pour la reconnaissance et la protection des d\u00e9fenseurs des droits humains qui sera ensuite remis aux autorit\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lors de sa pr\u00e9sentation de la loi type, \u00e9labor\u00e9e par ISHR, Ad\u00e9la\u00efde Etong Kame, responsable du programme Afrique \u00e0 ISHR, a soulign\u00e9 que \u00ab l\u2019objectif premier de la Loi type est de fournir aux d\u00e9fenseur.es un outil efficace et complet pour revendiquer leurs droits et prot\u00e9ger leur travail \u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Etant donn\u00e9e la pro\u00e9minence des attaques et restrictions auxquelles font faces les lanceurs d\u2019alertes \u00e0 Madagascar, les participants ont \u00e9galement eu l\u2019opportunit\u00e9 de b\u00e9n\u00e9ficier de l\u2019intervention de Me Henri Thulliez, directeur de la Plateforme de Protection des Lanceurs d\u2019Alerte en Afrique qui a pu discuter avec les participants de l\u2019importance de prot\u00e9ger les lanceurs d\u2019alerte et l\u2019opportunit\u00e9 d\u2019int\u00e9grer la protection des lanceurs d\u2019alerte au sein du projet de loi. \u00ab Int\u00e9grer la protection des lanceurs d\u2019alerte dans une telle loi permettrait de les prot\u00e9ger \u00e0 l\u2019encontre de toutes repr\u00e9sailles qui souvent les emp\u00eache d\u2019agir \u00bb d\u00e9clare Me Thulliez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les participants ont \u00e9galement pu interagir avec Marthe Pedan Coulibaly, Coordinatrice de la Coalition Ivoirienne des D\u00e9fenseurs des Droits Humains, qui a partag\u00e9 avec eux l\u2019exp\u00e9rience de la soci\u00e9t\u00e9 civile en C\u00f4te d\u2019Ivoire ayant amen\u00e9 \u00e0 l\u2019adoption d\u2019une loi sp\u00e9cifique des d\u00e9fenseur.es en 2014 et de l\u2019adoption de son d\u00e9cret d\u2019application en 2017. \u00ab La participation de la soci\u00e9t\u00e9 civile au processus de r\u00e9daction, d\u2019adoption et de mise en \u0153uvre de la loi est primordiale. Les efforts sont continues pour s\u2019assurer que la voix de la soci\u00e9t\u00e9 civile se retrouve dans le texte de loi et s\u2019assurer que l\u2019Etat n\u2019en profites pas pour restreindre d\u2019avantage les droits des d\u00e9fenseur.es dans le pays \u00bb d\u00e9clare Marthe Pedan Coulibaly.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enfin, les participants ont effectu\u00e9 de nombreux amendements au texte de loi y compris l\u2019ajout d\u2019une d\u00e9finition du lanceur d\u2019alerte inexistante dans le corpus juridique de Madagascar, le droit \u00e0 l\u2019acc\u00e8s \u00e0 l\u2019information, une protection sp\u00e9cifique des d\u00e9fenseur.es travaillant \u00e0 la protection de l\u2019environnement et la protection des d\u00e9fenseur.es contre toute diffamation ou harc\u00e8lement en ligne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toutes ces pr\u00e9occupations ont \u00e9t\u00e9 partag\u00e9es les 24, 25 et 26 Mars lors de l\u2019atelier organis\u00e9 par le HCDDED visant la finalisation du projet de loi pour la protection des d\u00e9fenseur.es \u00e0 Madagascar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ISHR et Transparency International \u2013 Madagascar r\u00e9it\u00e8rent leur volont\u00e9 de continuer \u00e0 collaborer avec les autorit\u00e9s en vue de l\u2019adoption de la loi nationale de protection des d\u00e9fenseur.es des droits humains en Madagascar, et de la d\u00e9signation d\u2019un m\u00e9canisme de protection efficace pour les d\u00e9fenseurs.\u00a0\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trouvez le contenu original <a href=\"http:\/\/archived2021.ishr.ch\/news\/madagascar-vers-une-meilleure-protection-des-defenseures-des-droits-humains\" target=\"_blank\" rel=\"noreferrer noopener\">ici<\/a> en fran\u00e7ais (<a href=\"https:\/\/ishr.ch\/\" target=\"_blank\" rel=\"noreferrer noopener\">ISHR<\/a>).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trouvez le project de loi ici. <\/p>\n","protected":false},"template":"","document-original-language":[354],"authorship":[206],"type-of-document":[164],"progress":[],"location":[211,364],"class_list":["post-4417","documents","type-documents","status-publish","hentry","document-original-language-fr-fr","authorship-societe-civile-et-universites","type-of-document-nouvelles","location-afrique","location-madagascar-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Madagascar: Atelier de l&#039;ISHR sur le projet de loi sur les d\u00e9fenseur\u00b7e\u00b7s des droits humains - Focus: The Observatory On Public Policies For Defenders<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.focus-obs.org\/fr\/documents\/madagascar-atelier-de-lishr-sur-le-projet-de-loi-sur-les-defenseur\u00b7e\u00b7s-des-droits-humains\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Madagascar: Atelier de l&#039;ISHR sur le projet de loi sur les d\u00e9fenseur\u00b7e\u00b7s des droits humains - Focus: The Observatory On Public Policies For Defenders\" \/>\n<meta property=\"og:description\" content=\"\u00ab\u00a0A Madagascar les attaques contre les d\u00e9fenseur.es des droits humains et les lanceurs d\u2019alerte se multiplient. Un avant-projet de loi sur la protection des d\u00e9fenseur.es avait \u00e9t\u00e9 pr\u00e9par\u00e9 en 2018 par le Minist\u00e8re de la Justice malgache, avec l\u2019appui du Haut-commissariat des Nations Unies pour les Droits de l\u2019Homme, et soumis \u00e0 une premi\u00e8re consultation [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.focus-obs.org\/fr\/documents\/madagascar-atelier-de-lishr-sur-le-projet-de-loi-sur-les-defenseur\u00b7e\u00b7s-des-droits-humains\/\" \/>\n<meta property=\"og:site_name\" content=\"Focus: The Observatory On Public Policies For Defenders\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-27T15:23:32+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/fr\\\/documents\\\/madagascar-atelier-de-lishr-sur-le-projet-de-loi-sur-les-defenseur%c2%b7e%c2%b7s-des-droits-humains\\\/\",\"url\":\"https:\\\/\\\/www.focus-obs.org\\\/fr\\\/documents\\\/madagascar-atelier-de-lishr-sur-le-projet-de-loi-sur-les-defenseur%c2%b7e%c2%b7s-des-droits-humains\\\/\",\"name\":\"Madagascar: Atelier de l'ISHR sur le projet de loi sur les d\u00e9fenseur\u00b7e\u00b7s des droits humains - Focus: The Observatory On Public Policies For Defenders\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/#website\"},\"datePublished\":\"2021-03-26T11:00:00+00:00\",\"dateModified\":\"2022-10-27T15:23:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/fr\\\/documents\\\/madagascar-atelier-de-lishr-sur-le-projet-de-loi-sur-les-defenseur%c2%b7e%c2%b7s-des-droits-humains\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.focus-obs.org\\\/fr\\\/documents\\\/madagascar-atelier-de-lishr-sur-le-projet-de-loi-sur-les-defenseur%c2%b7e%c2%b7s-des-droits-humains\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/fr\\\/documents\\\/madagascar-atelier-de-lishr-sur-le-projet-de-loi-sur-les-defenseur%c2%b7e%c2%b7s-des-droits-humains\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.focus-obs.org\\\/fr\\\/acceuil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Documents\",\"item\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/documents\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Madagascar: Atelier de l&#8217;ISHR sur le projet de loi sur les d\u00e9fenseur\u00b7e\u00b7s des droits humains\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/\",\"name\":\"Focus: The Observatory On Public Policies For Defenders\",\"description\":\"The Observatory On Public Policies For Defenders\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/#organization\",\"name\":\"Focus: The Observatory On Public Policies For Defenders\",\"url\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.focus-obs.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-focus-white-on-black-1.png\",\"contentUrl\":\"https:\\\/\\\/www.focus-obs.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-focus-white-on-black-1.png\",\"width\":2132,\"height\":735,\"caption\":\"Focus: The Observatory On Public Policies For Defenders\"},\"image\":{\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Madagascar: Atelier de l'ISHR sur le projet de loi sur les d\u00e9fenseur\u00b7e\u00b7s des droits humains - Focus: The Observatory On Public Policies For Defenders","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.focus-obs.org\/fr\/documents\/madagascar-atelier-de-lishr-sur-le-projet-de-loi-sur-les-defenseur\u00b7e\u00b7s-des-droits-humains\/","og_locale":"fr_FR","og_type":"article","og_title":"Madagascar: Atelier de l'ISHR sur le projet de loi sur les d\u00e9fenseur\u00b7e\u00b7s des droits humains - Focus: The Observatory On Public Policies For Defenders","og_description":"\u00ab\u00a0A Madagascar les attaques contre les d\u00e9fenseur.es des droits humains et les lanceurs d\u2019alerte se multiplient. Un avant-projet de loi sur la protection des d\u00e9fenseur.es avait \u00e9t\u00e9 pr\u00e9par\u00e9 en 2018 par le Minist\u00e8re de la Justice malgache, avec l\u2019appui du Haut-commissariat des Nations Unies pour les Droits de l\u2019Homme, et soumis \u00e0 une premi\u00e8re consultation [&hellip;]","og_url":"https:\/\/www.focus-obs.org\/fr\/documents\/madagascar-atelier-de-lishr-sur-le-projet-de-loi-sur-les-defenseur\u00b7e\u00b7s-des-droits-humains\/","og_site_name":"Focus: The Observatory On Public Policies For Defenders","article_modified_time":"2022-10-27T15:23:32+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.focus-obs.org\/fr\/documents\/madagascar-atelier-de-lishr-sur-le-projet-de-loi-sur-les-defenseur%c2%b7e%c2%b7s-des-droits-humains\/","url":"https:\/\/www.focus-obs.org\/fr\/documents\/madagascar-atelier-de-lishr-sur-le-projet-de-loi-sur-les-defenseur%c2%b7e%c2%b7s-des-droits-humains\/","name":"Madagascar: Atelier de l'ISHR sur le projet de loi sur les d\u00e9fenseur\u00b7e\u00b7s des droits humains - Focus: The Observatory On Public Policies For Defenders","isPartOf":{"@id":"https:\/\/www.focus-obs.org\/es\/#website"},"datePublished":"2021-03-26T11:00:00+00:00","dateModified":"2022-10-27T15:23:32+00:00","breadcrumb":{"@id":"https:\/\/www.focus-obs.org\/fr\/documents\/madagascar-atelier-de-lishr-sur-le-projet-de-loi-sur-les-defenseur%c2%b7e%c2%b7s-des-droits-humains\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.focus-obs.org\/fr\/documents\/madagascar-atelier-de-lishr-sur-le-projet-de-loi-sur-les-defenseur%c2%b7e%c2%b7s-des-droits-humains\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.focus-obs.org\/fr\/documents\/madagascar-atelier-de-lishr-sur-le-projet-de-loi-sur-les-defenseur%c2%b7e%c2%b7s-des-droits-humains\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.focus-obs.org\/fr\/acceuil\/"},{"@type":"ListItem","position":2,"name":"Documents","item":"https:\/\/www.focus-obs.org\/es\/documents\/"},{"@type":"ListItem","position":3,"name":"Madagascar: Atelier de l&#8217;ISHR sur le projet de loi sur les d\u00e9fenseur\u00b7e\u00b7s des droits humains"}]},{"@type":"WebSite","@id":"https:\/\/www.focus-obs.org\/es\/#website","url":"https:\/\/www.focus-obs.org\/es\/","name":"Focus: The Observatory On Public Policies For Defenders","description":"The Observatory On Public Policies For Defenders","publisher":{"@id":"https:\/\/www.focus-obs.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.focus-obs.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.focus-obs.org\/es\/#organization","name":"Focus: The Observatory On Public Policies For Defenders","url":"https:\/\/www.focus-obs.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.focus-obs.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.focus-obs.org\/wp-content\/uploads\/2021\/01\/logo-focus-white-on-black-1.png","contentUrl":"https:\/\/www.focus-obs.org\/wp-content\/uploads\/2021\/01\/logo-focus-white-on-black-1.png","width":2132,"height":735,"caption":"Focus: The Observatory On Public Policies For Defenders"},"image":{"@id":"https:\/\/www.focus-obs.org\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.focus-obs.org\/fr\/wp-json\/wp\/v2\/documents\/4417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focus-obs.org\/fr\/wp-json\/wp\/v2\/documents"}],"about":[{"href":"https:\/\/www.focus-obs.org\/fr\/wp-json\/wp\/v2\/types\/documents"}],"version-history":[{"count":6,"href":"https:\/\/www.focus-obs.org\/fr\/wp-json\/wp\/v2\/documents\/4417\/revisions"}],"predecessor-version":[{"id":7790,"href":"https:\/\/www.focus-obs.org\/fr\/wp-json\/wp\/v2\/documents\/4417\/revisions\/7790"}],"wp:attachment":[{"href":"https:\/\/www.focus-obs.org\/fr\/wp-json\/wp\/v2\/media?parent=4417"}],"wp:term":[{"taxonomy":"document-original-language","embeddable":true,"href":"https:\/\/www.focus-obs.org\/fr\/wp-json\/wp\/v2\/document-original-language?post=4417"},{"taxonomy":"authorship","embeddable":true,"href":"https:\/\/www.focus-obs.org\/fr\/wp-json\/wp\/v2\/authorship?post=4417"},{"taxonomy":"type-of-document","embeddable":true,"href":"https:\/\/www.focus-obs.org\/fr\/wp-json\/wp\/v2\/type-of-document?post=4417"},{"taxonomy":"progress","embeddable":true,"href":"https:\/\/www.focus-obs.org\/fr\/wp-json\/wp\/v2\/progress?post=4417"},{"taxonomy":"location","embeddable":true,"href":"https:\/\/www.focus-obs.org\/fr\/wp-json\/wp\/v2\/location?post=4417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}