{"id":11402,"date":"2023-11-16T11:24:31","date_gmt":"2023-11-16T10:24:31","guid":{"rendered":"https:\/\/www.focus-obs.org\/documents\/africa-webinar-laws-to-protect-human-rights-defenders-in-west-africa-and-the-great-lakes-region-are-they-fit-for-purpose-what-else-is-needed\/"},"modified":"2023-11-16T12:16:01","modified_gmt":"2023-11-16T11:16:01","slug":"africa-webinar-laws-to-protect-human-rights-defenders-in-west-africa-and-the-great-lakes-region-are-they-fit-for-purpose-what-else-is-needed","status":"publish","type":"documents","link":"https:\/\/www.focus-obs.org\/fr\/documents\/africa-webinar-laws-to-protect-human-rights-defenders-in-west-africa-and-the-great-lakes-region-are-they-fit-for-purpose-what-else-is-needed\/","title":{"rendered":"Afrique : Webinaire \u00ab\u00a0Les lois de protection des d\u00e9fenseur.e.s des droits humains en Afrique de l&rsquo;Ouest et dans la r\u00e9gion des Grands Lacs : Sont-elles adapt\u00e9es \u00e0 l&rsquo;objectif vis\u00e9 ? Que faut-il de plus ?\u00a0\u00bb"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le jeudi 27 juillet 2023, Protection International (PI) a organis\u00e9 un <a href=\"https:\/\/www.protectioninternational.org\/news\/join-the-webinar-laws-to-protect-human-rights-defenders-in-west-africa-and-the-great-lakes-region\/\" target=\"_blank\" data-type=\"URL\" data-id=\"https:\/\/www.protectioninternational.org\/news\/join-the-webinar-laws-to-protect-human-rights-defenders-in-west-africa-and-the-great-lakes-region\/\" rel=\"noreferrer noopener\">webinaire en ligne sur les politiques publiques<\/a> intitul\u00e9 \u00ab\u00a0Les lois pour prot\u00e9ger les d\u00e9fenseurs des droits de l&rsquo;homme en Afrique de l&rsquo;Ouest et dans la r\u00e9gion des Grands Lacs : sont-elles adapt\u00e9es ? Que faut-il d&rsquo;autre ?\u00a0\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cinq experts r\u00e9gionaux en politiques publiques ont particip\u00e9 en tant que pan\u00e9listes, dont Marthe Coulibaly, directrice de la Coalition Ivoirienne des D\u00e9fenseurs des Droits Humains (<a href=\"https:\/\/www.ci-ddh.org\/\" target=\"_blank\" data-type=\"URL\" data-id=\"https:\/\/www.ci-ddh.org\/\" rel=\"noreferrer noopener\">CIDDH<\/a>), Kanni Abdoulaye, coordinateur du R\u00e9seau Nig\u00e9rien des D\u00e9fenseurs des Droits Humains (<a href=\"https:\/\/rnddh-niger.org\/\" target=\"_blank\" data-type=\"URL\" data-id=\"https:\/\/rnddh-niger.org\/\" rel=\"noreferrer noopener\">RNDDH<\/a>), Catherine Mbui, responsable des d\u00e9fenseurs des droits de l&rsquo;homme \u00e0 la Commission Nationale des Droits de l&rsquo;Homme du Kenya (<a href=\"https:\/\/www.knchr.org\/\" target=\"_blank\" data-type=\"URL\" data-id=\"https:\/\/www.knchr.org\/\" rel=\"noreferrer noopener\">KNCHR<\/a>), Stella Yanda, secr\u00e9taire ex\u00e9cutive d&rsquo;INITIATIVES ALPHA, et Vicar Batundi, coordinateur national du Foyer de D\u00e9veloppement pour l&rsquo;Autopromotion des Pygm\u00e9es et des Indig\u00e8nes D\u00e9favoris\u00e9s (<a href=\"https:\/\/fdapid-hopeip.org\/\" target=\"_blank\" data-type=\"URL\" data-id=\"https:\/\/fdapid-hopeip.org\/\" rel=\"noreferrer noopener\">FDAPID<\/a>).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Plus de 140 personnes ont assist\u00e9 au webinaire et ont particip\u00e9 de mani\u00e8re tr\u00e8s active, posant de nombreuses questions engageantes. Avec l&rsquo;aide de nos pan\u00e9listes, nous avons pu plonger dans les politiques de protection existantes dans leurs pays tout en identifiant des voies d&rsquo;action pour la soci\u00e9t\u00e9 civile. Nous avons \u00e9galement discut\u00e9 de la mani\u00e8re dont les autorit\u00e9s \u00e9tatiques et les institutions nationales des droits de l&rsquo;homme peuvent favoriser un espace permettant \u00e0 une soci\u00e9t\u00e9 civile dynamique de prosp\u00e9rer en Afrique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le travail de Protection International dans le domaine des politiques publiques pour la protection des d\u00e9fenseurs des droits de l&rsquo;homme<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Contribuer \u00e0 de meilleures politiques publiques pour la protection des d\u00e9fenseurs des droits de l&rsquo;homme (DDHs) est au c\u0153ur de la strat\u00e9gie de Protection International (PI) : depuis le d\u00e9but des ann\u00e9es 2000, nous avons publi\u00e9<a href=\"https:\/\/www.protectioninternational.org\/tools\/research-publications\/\" target=\"_blank\" data-type=\"URL\" data-id=\"https:\/\/www.protectioninternational.org\/tools\/research-publications\/\" rel=\"noreferrer noopener\"> plusieurs rapports et analyses sur ce sujet<\/a> et nous avons soutenu le travail des autorit\u00e9s locales et de la soci\u00e9t\u00e9 civile en mati\u00e8re de politiques publiques dans certains pays d&rsquo;Afrique, d&rsquo;Am\u00e9rique latine et d&rsquo;Asie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce sujet est au c\u0153ur de nos interventions parce qu&rsquo;en fin de compte, l&rsquo;obligation de prot\u00e9ger les d\u00e9fenseurs contre les menaces et les attaques incombe aux autorit\u00e9s de l&rsquo;\u00c9tat. De plus, l&rsquo;adoption de politiques publiques visant \u00e0 prot\u00e9ger les d\u00e9fenseurs et leur droit \u00e0 d\u00e9fendre les droits de l&rsquo;homme peut contribuer \u00e0 r\u00e9soudre ce probl\u00e8me complexe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cependant, les politiques publiques nationales visant \u00e0 prot\u00e9ger les DDHs en danger rev\u00eatent de nombreuses formes : il peut s&rsquo;agir de lois nationales, de l\u00e9gislations subnationales, de m\u00e9canismes de protection, de politiques et de directives \u00e9mises par des NHRIs ind\u00e9pendantes, entre autres. En Am\u00e9rique latine, par exemple, on observe une forte concentration sur les m\u00e9canismes de protection, principalement en raison des niveaux \u00e9lev\u00e9s de violence et de criminalit\u00e9 qui touchent les DDHs, tandis qu&rsquo;en Afrique, il y a eu une prolif\u00e9ration de lois nationales, principalement en Afrique de l&rsquo;Ouest, et de l\u00e9gislations subnationales en R\u00e9publique d\u00e9mocratique du Congo (RDC). Cependant, cette l\u00e9gislation est davantage une d\u00e9claration d&rsquo;intention des autorit\u00e9s de l&rsquo;\u00c9tat qu&rsquo;un moyen efficace de prot\u00e9ger les DDHs : nous avons constat\u00e9 peu ou pas de mise en \u0153uvre en ce qui concerne la pr\u00e9vention et la prise en charge des menaces et des agressions.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Malheureusement, les deux r\u00e9gions partagent un d\u00e9nominateur commun : le foss\u00e9 de la mise en \u0153uvre. M\u00eame s&rsquo;il existe des m\u00e9canismes et des lois dans de nombreux pays, les d\u00e9fenseurs continuent d&rsquo;\u00eatre pris pour cible et attaqu\u00e9s avec un haut niveau d&rsquo;impunit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le cadre de notre travail dans ce domaine, Protection International a cr\u00e9\u00e9 l&rsquo;Observatoire FOCUS, une plateforme en ligne qui vise \u00e0 centraliser les connaissances sur les politiques publiques de protection des DDHs dans le monde entier, \u00e0 suivre les mises \u00e0 jour et \u00e0 en analyser la port\u00e9e et l&rsquo;efficacit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Plus r\u00e9cemment, le bureau de PI en RDC et son \u00e9quipe mondiale bas\u00e9e \u00e0 Bruxelles ont entrepris un projet de recherche collaboratif ax\u00e9 sur la mani\u00e8re dont les DDHs per\u00e7oivent l&rsquo;impact de la l\u00e9gislation subnationale de protection (d\u00e9crets provinciaux) du Nord et du Sud-Kivu sur leur travail en mati\u00e8re de droits de l&rsquo;homme. Les r\u00e9sultats de cette recherche <strong><a href=\"https:\/\/www.focus-obs.org\/fr\/documents\/drcthe-right-to-defend-human-rights-not-for-all-a-case-study-of-public-policies-on-human-rights-defenders-in-the-drc\/\" target=\"_blank\" data-type=\"URL\" data-id=\"https:\/\/www.focus-obs.org\/fr\/documents\/drcthe-right-to-defend-human-rights-not-for-all-a-case-study-of-public-policies-on-human-rights-defenders-in-the-drc\/\" rel=\"noreferrer noopener\">peut \u00eatre examin\u00e9e<\/a><\/strong> sur le site web de l&rsquo;Observatoire FOCUS.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Principales conclusions du webinaire<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Parmi les principales conclusions du webinaire, nous pourrions mettre en avant les suivantes :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Combler le foss\u00e9 de la mise&nbsp;en \u0153uvre et prot\u00e9ger efficacement les DDHs n\u00e9cessite une volont\u00e9 politique. Les hommes politiques et les fonctionnaires gouvernementaux doivent reconna\u00eetre le r\u00f4le que jouent les d\u00e9fenseurs des droits de l&rsquo;homme dans la construction d&rsquo;une soci\u00e9t\u00e9 d\u00e9mocratique et plus juste.<\/li>\n\n\n\n<li>L&rsquo;adoption de politiques publiques visant \u00e0 prot\u00e9ger les DDHs et leur droit \u00e0 d\u00e9fendre les droits de l&rsquo;homme est un processus complexe qui d\u00e9pend des r\u00e9alit\u00e9s sociopolitiques et institutionnelles de chaque pays. Les efforts peuvent mettre plusieurs ann\u00e9es \u00e0 porter leurs fruits, comme le montre le cas du Niger. De plus, l&rsquo;adoption de lois nationales n&rsquo;est pas la fin, mais le d\u00e9but d&rsquo;un voyage : comme le montre le cas de la C\u00f4te d&rsquo;Ivoire, la soci\u00e9t\u00e9 civile a collabor\u00e9 avec diff\u00e9rentes autorit\u00e9s de l&rsquo;\u00c9tat dans le but d&rsquo;adopter des instruments politiques suppl\u00e9mentaires permettant la mise en \u0153uvre correcte de la loi nationale.<\/li>\n\n\n\n<li>La participation de la soci\u00e9t\u00e9 civile au d\u00e9veloppement des politiques de protection est essentielle. Les d\u00e9cideurs politiques devraient cr\u00e9er des espaces pour dialoguer avec les OSC et d&rsquo;autres parties prenantes (y compris les NHRIs) afin de discuter correctement et d&rsquo;inclure les besoins de protection des d\u00e9fenseurs des droits de la femme et des DDHs issus de groupes vuln\u00e9rables, y compris les personnes handicap\u00e9es. Un tel dialogue entre les DDHs et les autorit\u00e9s locales est \u00e9galement essentiel pour cr\u00e9er un environnement favorable \u00e0 la d\u00e9fense des droits de l&rsquo;homme.<\/li>\n\n\n\n<li>Les r\u00e9seaux de protection sont \u00e9galement essentiels : les r\u00e9seaux de protection au niveau national devraient inclure les DDHs et leurs OSC au niveau local et \u00e0 travers le pays. Ces r\u00e9seaux devraient \u00eatre renforc\u00e9s par le biais de liens avec les r\u00e9seaux r\u00e9gionaux africains ainsi qu&rsquo;avec des partenaires internationaux et des parties prenantes. Le cas de la RDC montre comment les ambassades et les missions diplomatiques ont soutenu les efforts du gouvernement, du parlement et des organisations de la soci\u00e9t\u00e9 civile pour adopter une l\u00e9gislation de protection des DDHs dans le pays.<\/li>\n\n\n\n<li>Les r\u00e9seaux peuvent \u00e9galement jouer un r\u00f4le important en mati\u00e8re de suivi et d&rsquo;\u00e9valuation des politiques publiques de protection des DDH. Tout en plaidant en faveur de lois et de politiques publiques qui prot\u00e8gent les DDHs et leur droit \u00e0 d\u00e9fendre les droits de l&rsquo;homme, les d\u00e9fenseurs et leurs OSC doivent surveiller la l\u00e9gislation restrictive et chercher \u00e0 l&rsquo;abroger ou du moins \u00e0 la modifier.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Le webinaire a \u00e9t\u00e9 organis\u00e9 dans le cadre de deux projets en R\u00e9publique d\u00e9mocratique du Congo et en Afrique de l&rsquo;Ouest, avec le soutien financier du gouvernement allemand. Nous avons \u00e9galement pu compter sur la solide collaboration de nos partenaires : Solidarit\u00e9 F\u00e9minine pour la Paix et le D\u00e9veloppement Int\u00e9gral (SOFEPADI), Coalition des Femmes D\u00e9fenseuses des Droits Humains, West African Human Rights Defenders Network et Partnership for Justice<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Protection International tient \u00e0 remercier ses bailleurs de fonds pour leur pr\u00e9cieux soutien<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/www.focus-obs.org\/wp-content\/uploads\/2023\/11\/th-533410744-1.jpg\" alt=\"\" class=\"wp-image-11420\" width=\"185\" height=\"108\" srcset=\"https:\/\/www.focus-obs.org\/wp-content\/uploads\/2023\/11\/th-533410744-1.jpg 474w, https:\/\/www.focus-obs.org\/wp-content\/uploads\/2023\/11\/th-533410744-1-300x174.jpg 300w\" sizes=\"(max-width: 185px) 100vw, 185px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><a id=\"_msocom_1\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a id=\"_msocom_2\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"template":"","document-original-language":[351],"authorship":[437],"type-of-document":[166],"progress":[],"location":[211],"class_list":["post-11402","documents","type-documents","status-publish","hentry","document-original-language-en-fr","authorship-protection-international-fr","type-of-document-etude-ou-analyse","location-afrique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Afrique : Webinaire &quot;Les lois de protection des d\u00e9fenseur.e.s des droits humains en Afrique de l&#039;Ouest et dans la r\u00e9gion des Grands Lacs : Sont-elles adapt\u00e9es \u00e0 l&#039;objectif vis\u00e9 ? Que faut-il de plus ?&quot; - Focus: The Observatory On Public Policies For Defenders<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.focus-obs.org\/fr\/documents\/africa-webinar-laws-to-protect-human-rights-defenders-in-west-africa-and-the-great-lakes-region-are-they-fit-for-purpose-what-else-is-needed\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Afrique : Webinaire &quot;Les lois de protection des d\u00e9fenseur.e.s des droits humains en Afrique de l&#039;Ouest et dans la r\u00e9gion des Grands Lacs : Sont-elles adapt\u00e9es \u00e0 l&#039;objectif vis\u00e9 ? Que faut-il de plus ?&quot; - Focus: The Observatory On Public Policies For Defenders\" \/>\n<meta property=\"og:description\" content=\"Le jeudi 27 juillet 2023, Protection International (PI) a organis\u00e9 un webinaire en ligne sur les politiques publiques intitul\u00e9 \u00ab\u00a0Les lois pour prot\u00e9ger les d\u00e9fenseurs des droits de l&rsquo;homme en Afrique de l&rsquo;Ouest et dans la r\u00e9gion des Grands Lacs : sont-elles adapt\u00e9es ? Que faut-il d&rsquo;autre ?\u00a0\u00bb Cinq experts r\u00e9gionaux en politiques publiques ont [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.focus-obs.org\/fr\/documents\/africa-webinar-laws-to-protect-human-rights-defenders-in-west-africa-and-the-great-lakes-region-are-they-fit-for-purpose-what-else-is-needed\/\" \/>\n<meta property=\"og:site_name\" content=\"Focus: The Observatory On Public Policies For Defenders\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-16T11:16:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.focus-obs.org\/wp-content\/uploads\/2023\/11\/th-533410744-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"474\" \/>\n\t<meta property=\"og:image:height\" content=\"275\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/fr\\\/documents\\\/africa-webinar-laws-to-protect-human-rights-defenders-in-west-africa-and-the-great-lakes-region-are-they-fit-for-purpose-what-else-is-needed\\\/\",\"url\":\"https:\\\/\\\/www.focus-obs.org\\\/fr\\\/documents\\\/africa-webinar-laws-to-protect-human-rights-defenders-in-west-africa-and-the-great-lakes-region-are-they-fit-for-purpose-what-else-is-needed\\\/\",\"name\":\"Afrique : Webinaire \\\"Les lois de protection des d\u00e9fenseur.e.s des droits humains en Afrique de l'Ouest et dans la r\u00e9gion des Grands Lacs : Sont-elles adapt\u00e9es \u00e0 l'objectif vis\u00e9 ? Que faut-il de plus ?\\\" - Focus: The Observatory On Public Policies For Defenders\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/fr\\\/documents\\\/africa-webinar-laws-to-protect-human-rights-defenders-in-west-africa-and-the-great-lakes-region-are-they-fit-for-purpose-what-else-is-needed\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/fr\\\/documents\\\/africa-webinar-laws-to-protect-human-rights-defenders-in-west-africa-and-the-great-lakes-region-are-they-fit-for-purpose-what-else-is-needed\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.focus-obs.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/th-533410744-1.jpg\",\"datePublished\":\"2023-11-16T10:24:31+00:00\",\"dateModified\":\"2023-11-16T11:16:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/fr\\\/documents\\\/africa-webinar-laws-to-protect-human-rights-defenders-in-west-africa-and-the-great-lakes-region-are-they-fit-for-purpose-what-else-is-needed\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.focus-obs.org\\\/fr\\\/documents\\\/africa-webinar-laws-to-protect-human-rights-defenders-in-west-africa-and-the-great-lakes-region-are-they-fit-for-purpose-what-else-is-needed\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/fr\\\/documents\\\/africa-webinar-laws-to-protect-human-rights-defenders-in-west-africa-and-the-great-lakes-region-are-they-fit-for-purpose-what-else-is-needed\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.focus-obs.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/th-533410744-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.focus-obs.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/th-533410744-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/fr\\\/documents\\\/africa-webinar-laws-to-protect-human-rights-defenders-in-west-africa-and-the-great-lakes-region-are-they-fit-for-purpose-what-else-is-needed\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.focus-obs.org\\\/fr\\\/acceuil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Documents\",\"item\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/documents\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Afrique : Webinaire &#8220;Les lois de protection des d\u00e9fenseur.e.s des droits humains en Afrique de l&#8217;Ouest et dans la r\u00e9gion des Grands Lacs : Sont-elles adapt\u00e9es \u00e0 l&#8217;objectif vis\u00e9 ? Que faut-il de plus ?&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/\",\"name\":\"Focus: The Observatory On Public Policies For Defenders\",\"description\":\"The Observatory On Public Policies For Defenders\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/#organization\",\"name\":\"Focus: The Observatory On Public Policies For Defenders\",\"url\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.focus-obs.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-focus-white-on-black-1.png\",\"contentUrl\":\"https:\\\/\\\/www.focus-obs.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-focus-white-on-black-1.png\",\"width\":2132,\"height\":735,\"caption\":\"Focus: The Observatory On Public Policies For Defenders\"},\"image\":{\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Afrique : Webinaire \"Les lois de protection des d\u00e9fenseur.e.s des droits humains en Afrique de l'Ouest et dans la r\u00e9gion des Grands Lacs : Sont-elles adapt\u00e9es \u00e0 l'objectif vis\u00e9 ? Que faut-il de plus ?\" - Focus: The Observatory On Public Policies For Defenders","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.focus-obs.org\/fr\/documents\/africa-webinar-laws-to-protect-human-rights-defenders-in-west-africa-and-the-great-lakes-region-are-they-fit-for-purpose-what-else-is-needed\/","og_locale":"fr_FR","og_type":"article","og_title":"Afrique : Webinaire \"Les lois de protection des d\u00e9fenseur.e.s des droits humains en Afrique de l'Ouest et dans la r\u00e9gion des Grands Lacs : Sont-elles adapt\u00e9es \u00e0 l'objectif vis\u00e9 ? Que faut-il de plus ?\" - Focus: The Observatory On Public Policies For Defenders","og_description":"Le jeudi 27 juillet 2023, Protection International (PI) a organis\u00e9 un webinaire en ligne sur les politiques publiques intitul\u00e9 \u00ab\u00a0Les lois pour prot\u00e9ger les d\u00e9fenseurs des droits de l&rsquo;homme en Afrique de l&rsquo;Ouest et dans la r\u00e9gion des Grands Lacs : sont-elles adapt\u00e9es ? Que faut-il d&rsquo;autre ?\u00a0\u00bb Cinq experts r\u00e9gionaux en politiques publiques ont [&hellip;]","og_url":"https:\/\/www.focus-obs.org\/fr\/documents\/africa-webinar-laws-to-protect-human-rights-defenders-in-west-africa-and-the-great-lakes-region-are-they-fit-for-purpose-what-else-is-needed\/","og_site_name":"Focus: The Observatory On Public Policies For Defenders","article_modified_time":"2023-11-16T11:16:01+00:00","og_image":[{"width":474,"height":275,"url":"https:\/\/www.focus-obs.org\/wp-content\/uploads\/2023\/11\/th-533410744-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.focus-obs.org\/fr\/documents\/africa-webinar-laws-to-protect-human-rights-defenders-in-west-africa-and-the-great-lakes-region-are-they-fit-for-purpose-what-else-is-needed\/","url":"https:\/\/www.focus-obs.org\/fr\/documents\/africa-webinar-laws-to-protect-human-rights-defenders-in-west-africa-and-the-great-lakes-region-are-they-fit-for-purpose-what-else-is-needed\/","name":"Afrique : Webinaire \"Les lois de protection des d\u00e9fenseur.e.s des droits humains en Afrique de l'Ouest et dans la r\u00e9gion des Grands Lacs : Sont-elles adapt\u00e9es \u00e0 l'objectif vis\u00e9 ? Que faut-il de plus ?\" - Focus: The Observatory On Public Policies For Defenders","isPartOf":{"@id":"https:\/\/www.focus-obs.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.focus-obs.org\/fr\/documents\/africa-webinar-laws-to-protect-human-rights-defenders-in-west-africa-and-the-great-lakes-region-are-they-fit-for-purpose-what-else-is-needed\/#primaryimage"},"image":{"@id":"https:\/\/www.focus-obs.org\/fr\/documents\/africa-webinar-laws-to-protect-human-rights-defenders-in-west-africa-and-the-great-lakes-region-are-they-fit-for-purpose-what-else-is-needed\/#primaryimage"},"thumbnailUrl":"https:\/\/www.focus-obs.org\/wp-content\/uploads\/2023\/11\/th-533410744-1.jpg","datePublished":"2023-11-16T10:24:31+00:00","dateModified":"2023-11-16T11:16:01+00:00","breadcrumb":{"@id":"https:\/\/www.focus-obs.org\/fr\/documents\/africa-webinar-laws-to-protect-human-rights-defenders-in-west-africa-and-the-great-lakes-region-are-they-fit-for-purpose-what-else-is-needed\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.focus-obs.org\/fr\/documents\/africa-webinar-laws-to-protect-human-rights-defenders-in-west-africa-and-the-great-lakes-region-are-they-fit-for-purpose-what-else-is-needed\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.focus-obs.org\/fr\/documents\/africa-webinar-laws-to-protect-human-rights-defenders-in-west-africa-and-the-great-lakes-region-are-they-fit-for-purpose-what-else-is-needed\/#primaryimage","url":"https:\/\/www.focus-obs.org\/wp-content\/uploads\/2023\/11\/th-533410744-1.jpg","contentUrl":"https:\/\/www.focus-obs.org\/wp-content\/uploads\/2023\/11\/th-533410744-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.focus-obs.org\/fr\/documents\/africa-webinar-laws-to-protect-human-rights-defenders-in-west-africa-and-the-great-lakes-region-are-they-fit-for-purpose-what-else-is-needed\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.focus-obs.org\/fr\/acceuil\/"},{"@type":"ListItem","position":2,"name":"Documents","item":"https:\/\/www.focus-obs.org\/es\/documents\/"},{"@type":"ListItem","position":3,"name":"Afrique : Webinaire &#8220;Les lois de protection des d\u00e9fenseur.e.s des droits humains en Afrique de l&#8217;Ouest et dans la r\u00e9gion des Grands Lacs : Sont-elles adapt\u00e9es \u00e0 l&#8217;objectif vis\u00e9 ? Que faut-il de plus ?&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.focus-obs.org\/es\/#website","url":"https:\/\/www.focus-obs.org\/es\/","name":"Focus: The Observatory On Public Policies For Defenders","description":"The Observatory On Public Policies For Defenders","publisher":{"@id":"https:\/\/www.focus-obs.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.focus-obs.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.focus-obs.org\/es\/#organization","name":"Focus: The Observatory On Public Policies For Defenders","url":"https:\/\/www.focus-obs.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.focus-obs.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.focus-obs.org\/wp-content\/uploads\/2021\/01\/logo-focus-white-on-black-1.png","contentUrl":"https:\/\/www.focus-obs.org\/wp-content\/uploads\/2021\/01\/logo-focus-white-on-black-1.png","width":2132,"height":735,"caption":"Focus: The Observatory On Public Policies For Defenders"},"image":{"@id":"https:\/\/www.focus-obs.org\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.focus-obs.org\/fr\/wp-json\/wp\/v2\/documents\/11402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focus-obs.org\/fr\/wp-json\/wp\/v2\/documents"}],"about":[{"href":"https:\/\/www.focus-obs.org\/fr\/wp-json\/wp\/v2\/types\/documents"}],"version-history":[{"count":4,"href":"https:\/\/www.focus-obs.org\/fr\/wp-json\/wp\/v2\/documents\/11402\/revisions"}],"predecessor-version":[{"id":11423,"href":"https:\/\/www.focus-obs.org\/fr\/wp-json\/wp\/v2\/documents\/11402\/revisions\/11423"}],"wp:attachment":[{"href":"https:\/\/www.focus-obs.org\/fr\/wp-json\/wp\/v2\/media?parent=11402"}],"wp:term":[{"taxonomy":"document-original-language","embeddable":true,"href":"https:\/\/www.focus-obs.org\/fr\/wp-json\/wp\/v2\/document-original-language?post=11402"},{"taxonomy":"authorship","embeddable":true,"href":"https:\/\/www.focus-obs.org\/fr\/wp-json\/wp\/v2\/authorship?post=11402"},{"taxonomy":"type-of-document","embeddable":true,"href":"https:\/\/www.focus-obs.org\/fr\/wp-json\/wp\/v2\/type-of-document?post=11402"},{"taxonomy":"progress","embeddable":true,"href":"https:\/\/www.focus-obs.org\/fr\/wp-json\/wp\/v2\/progress?post=11402"},{"taxonomy":"location","embeddable":true,"href":"https:\/\/www.focus-obs.org\/fr\/wp-json\/wp\/v2\/location?post=11402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}