{"id":3498,"date":"2021-07-12T17:09:18","date_gmt":"2021-07-12T15:09:18","guid":{"rendered":"https:\/\/www.focus-obs.org\/documents\/proyecto-de-ley-de-proteccion-de-los-defensores-de-los-derechos-humanos-2018\/"},"modified":"2022-11-08T15:32:08","modified_gmt":"2022-11-08T14:32:08","slug":"india-proyecto-de-ley-de-proteccion-de-los-defensores-de-los-derechos-humanos","status":"publish","type":"documents","link":"https:\/\/www.focus-obs.org\/es\/documents\/india-proyecto-de-ley-de-proteccion-de-los-defensores-de-los-derechos-humanos\/","title":{"rendered":"India: Proyecto de ley de protecci\u00f3n de los defensores de los derechos humanos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En 2018, el diputado Shri A.P. J Ithender Reddy present\u00f3 el proyecto de ley de protecci\u00f3n de las personas defensoras de los derechos humanos (proyecto de ley n\u00ba 222) en la Lok Sabha, la c\u00e1mara baja del Parlamento indio. El proyecto de ley, que se llamar\u00e1 Ley de Protecci\u00f3n de los Defensores de los Derechos Humanos, tiene como objetivo garantizar la protecci\u00f3n de las personas, grupos, asociaciones que se dedican a la protecci\u00f3n y promoci\u00f3n de los derechos humanos y las libertades fundamentales en la India.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Hasta el momento, el proceso parece no tener m\u00e1s recorrido. Teniendo en cuenta que el proyecto de ley ha permanecido pendiente durante m\u00e1s de cuatro a\u00f1os y que desde entonces ha sido eliminado del registro oficial. Por lo tanto, consideramos este proceso como abandonado (actualisaci\u00f3n el 08\/11\/2022).<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Encuentren el documento original <a href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=&amp;cad=rja&amp;uact=8&amp;ved=2ahUKEwjk27CK5d3xAhXS3YUKHVh2AAsQFnoECAgQAw&amp;url=http%3A%2F%2F164.100.47.4%2Fbillstexts%2Flsbilltexts%2Fasintroduced%2F2467as.pdf&amp;usg=AOvVaw1ZzGWeusM8J_l_ZFlNyZA-\" data-type=\"URL\" data-id=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=&amp;cad=rja&amp;uact=8&amp;ved=2ahUKEwjk27CK5d3xAhXS3YUKHVh2AAsQFnoECAgQAw&amp;url=http%3A%2F%2F164.100.47.4%2Fbillstexts%2Flsbilltexts%2Fasintroduced%2F2467as.pdf&amp;usg=AOvVaw1ZzGWeusM8J_l_ZFlNyZA-\" target=\"_blank\" rel=\"noreferrer noopener\">aqu\u00ed<\/a> en ingl\u00e9s. <\/p>\n","protected":false},"template":"","document-original-language":[350],"authorship":[136],"type-of-document":[141],"progress":[150],"location":[174,319],"class_list":["post-3498","documents","type-documents","status-publish","hentry","document-original-language-en-es","authorship-autoridades-e-instituciones-nacionales","type-of-document-ley-o-decreto-o-similar-incluidas-las-propuestas","progress-abandonado-o-abrogado","location-asia","location-india-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>India: Proyecto de ley de protecci\u00f3n de los defensores de los derechos humanos - Focus: The Observatory On Public Policies For Defenders<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.focus-obs.org\/es\/documents\/india-proyecto-de-ley-de-proteccion-de-los-defensores-de-los-derechos-humanos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"India: Proyecto de ley de protecci\u00f3n de los defensores de los derechos humanos - Focus: The Observatory On Public Policies For Defenders\" \/>\n<meta property=\"og:description\" content=\"En 2018, el diputado Shri A.P. J Ithender Reddy present\u00f3 el proyecto de ley de protecci\u00f3n de las personas defensoras de los derechos humanos (proyecto de ley n\u00ba 222) en la Lok Sabha, la c\u00e1mara baja del Parlamento indio. El proyecto de ley, que se llamar\u00e1 Ley de Protecci\u00f3n de los Defensores de los Derechos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.focus-obs.org\/es\/documents\/india-proyecto-de-ley-de-proteccion-de-los-defensores-de-los-derechos-humanos\/\" \/>\n<meta property=\"og:site_name\" content=\"Focus: The Observatory On Public Policies For Defenders\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-08T14:32:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/documents\\\/india-proyecto-de-ley-de-proteccion-de-los-defensores-de-los-derechos-humanos\\\/\",\"url\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/documents\\\/india-proyecto-de-ley-de-proteccion-de-los-defensores-de-los-derechos-humanos\\\/\",\"name\":\"India: Proyecto de ley de protecci\u00f3n de los defensores de los derechos humanos - Focus: The Observatory On Public Policies For Defenders\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/#website\"},\"datePublished\":\"2021-07-12T15:09:18+00:00\",\"dateModified\":\"2022-11-08T14:32:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/documents\\\/india-proyecto-de-ley-de-proteccion-de-los-defensores-de-los-derechos-humanos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/documents\\\/india-proyecto-de-ley-de-proteccion-de-los-defensores-de-los-derechos-humanos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/documents\\\/india-proyecto-de-ley-de-proteccion-de-los-defensores-de-los-derechos-humanos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Documents\",\"item\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/documents\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"India: Proyecto de ley de protecci\u00f3n de los defensores de los derechos humanos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/\",\"name\":\"Focus: The Observatory On Public Policies For Defenders\",\"description\":\"The Observatory On Public Policies For Defenders\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/#organization\",\"name\":\"Focus: The Observatory On Public Policies For Defenders\",\"url\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.focus-obs.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-focus-white-on-black-1.png\",\"contentUrl\":\"https:\\\/\\\/www.focus-obs.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-focus-white-on-black-1.png\",\"width\":2132,\"height\":735,\"caption\":\"Focus: The Observatory On Public Policies For Defenders\"},\"image\":{\"@id\":\"https:\\\/\\\/www.focus-obs.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"India: Proyecto de ley de protecci\u00f3n de los defensores de los derechos humanos - Focus: The Observatory On Public Policies For Defenders","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.focus-obs.org\/es\/documents\/india-proyecto-de-ley-de-proteccion-de-los-defensores-de-los-derechos-humanos\/","og_locale":"es_ES","og_type":"article","og_title":"India: Proyecto de ley de protecci\u00f3n de los defensores de los derechos humanos - Focus: The Observatory On Public Policies For Defenders","og_description":"En 2018, el diputado Shri A.P. J Ithender Reddy present\u00f3 el proyecto de ley de protecci\u00f3n de las personas defensoras de los derechos humanos (proyecto de ley n\u00ba 222) en la Lok Sabha, la c\u00e1mara baja del Parlamento indio. El proyecto de ley, que se llamar\u00e1 Ley de Protecci\u00f3n de los Defensores de los Derechos [&hellip;]","og_url":"https:\/\/www.focus-obs.org\/es\/documents\/india-proyecto-de-ley-de-proteccion-de-los-defensores-de-los-derechos-humanos\/","og_site_name":"Focus: The Observatory On Public Policies For Defenders","article_modified_time":"2022-11-08T14:32:08+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.focus-obs.org\/es\/documents\/india-proyecto-de-ley-de-proteccion-de-los-defensores-de-los-derechos-humanos\/","url":"https:\/\/www.focus-obs.org\/es\/documents\/india-proyecto-de-ley-de-proteccion-de-los-defensores-de-los-derechos-humanos\/","name":"India: Proyecto de ley de protecci\u00f3n de los defensores de los derechos humanos - Focus: The Observatory On Public Policies For Defenders","isPartOf":{"@id":"https:\/\/www.focus-obs.org\/es\/#website"},"datePublished":"2021-07-12T15:09:18+00:00","dateModified":"2022-11-08T14:32:08+00:00","breadcrumb":{"@id":"https:\/\/www.focus-obs.org\/es\/documents\/india-proyecto-de-ley-de-proteccion-de-los-defensores-de-los-derechos-humanos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.focus-obs.org\/es\/documents\/india-proyecto-de-ley-de-proteccion-de-los-defensores-de-los-derechos-humanos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.focus-obs.org\/es\/documents\/india-proyecto-de-ley-de-proteccion-de-los-defensores-de-los-derechos-humanos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.focus-obs.org\/es\/"},{"@type":"ListItem","position":2,"name":"Documents","item":"https:\/\/www.focus-obs.org\/es\/documents\/"},{"@type":"ListItem","position":3,"name":"India: Proyecto de ley de protecci\u00f3n de los defensores de los derechos humanos"}]},{"@type":"WebSite","@id":"https:\/\/www.focus-obs.org\/es\/#website","url":"https:\/\/www.focus-obs.org\/es\/","name":"Focus: The Observatory On Public Policies For Defenders","description":"The Observatory On Public Policies For Defenders","publisher":{"@id":"https:\/\/www.focus-obs.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.focus-obs.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.focus-obs.org\/es\/#organization","name":"Focus: The Observatory On Public Policies For Defenders","url":"https:\/\/www.focus-obs.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.focus-obs.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.focus-obs.org\/wp-content\/uploads\/2021\/01\/logo-focus-white-on-black-1.png","contentUrl":"https:\/\/www.focus-obs.org\/wp-content\/uploads\/2021\/01\/logo-focus-white-on-black-1.png","width":2132,"height":735,"caption":"Focus: The Observatory On Public Policies For Defenders"},"image":{"@id":"https:\/\/www.focus-obs.org\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.focus-obs.org\/es\/wp-json\/wp\/v2\/documents\/3498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.focus-obs.org\/es\/wp-json\/wp\/v2\/documents"}],"about":[{"href":"https:\/\/www.focus-obs.org\/es\/wp-json\/wp\/v2\/types\/documents"}],"version-history":[{"count":2,"href":"https:\/\/www.focus-obs.org\/es\/wp-json\/wp\/v2\/documents\/3498\/revisions"}],"predecessor-version":[{"id":8494,"href":"https:\/\/www.focus-obs.org\/es\/wp-json\/wp\/v2\/documents\/3498\/revisions\/8494"}],"wp:attachment":[{"href":"https:\/\/www.focus-obs.org\/es\/wp-json\/wp\/v2\/media?parent=3498"}],"wp:term":[{"taxonomy":"document-original-language","embeddable":true,"href":"https:\/\/www.focus-obs.org\/es\/wp-json\/wp\/v2\/document-original-language?post=3498"},{"taxonomy":"authorship","embeddable":true,"href":"https:\/\/www.focus-obs.org\/es\/wp-json\/wp\/v2\/authorship?post=3498"},{"taxonomy":"type-of-document","embeddable":true,"href":"https:\/\/www.focus-obs.org\/es\/wp-json\/wp\/v2\/type-of-document?post=3498"},{"taxonomy":"progress","embeddable":true,"href":"https:\/\/www.focus-obs.org\/es\/wp-json\/wp\/v2\/progress?post=3498"},{"taxonomy":"location","embeddable":true,"href":"https:\/\/www.focus-obs.org\/es\/wp-json\/wp\/v2\/location?post=3498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}